{"id":20285,"date":"2025-12-26T12:15:49","date_gmt":"2025-12-26T11:15:49","guid":{"rendered":"https:\/\/www.accountable.eu\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/"},"modified":"2026-05-07T10:19:20","modified_gmt":"2026-05-07T08:19:20","slug":"je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant","status":"publish","type":"help_center","link":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/","title":{"rendered":"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ?"},"content":{"rendered":"<p class=\"no-margin\">\n<h2 id=\"h_6eca822b81\">\ud83d\udee0 Voici comment corriger votre type de TVA incorrect : notre guide simple et rapide<\/h2>\n<p class=\"no-margin\">Choisir un mauvais type de TVA peut poser probl\u00e8me, notamment lors de vos d\u00e9clarations. Voici ce que cela peut entra\u00eener :<\/p>\n<ul>\n<li>\n<p class=\"no-margin\"><b>Pas de d\u00e9claration de TVA disponible<\/b><br \/>Si le type de TVA s\u00e9lectionn\u00e9 n\u2019est pas le bon, vous ne pourrez pas soumettre votre d\u00e9claration via Accountable. Cela peut entra\u00eener des retards ou des amendes.<br \/>\u200b<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\"><b>Erreurs dans la d\u00e9claration automatique<\/b><br \/>Le SPF d\u00e9clare maintenant automatiquement votre TVA. Si le type de TVA est incorrect, la d\u00e9claration ne refl\u00e9tera pas vos obligations r\u00e9elles, ce qui peut entra\u00eener des erreurs.<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">\ud83d\udc49 <b>Bonne nouvelle : il est tout \u00e0 fait possible de corriger cela !<\/b><br \/>\u200b<br \/>En ajustant rapidement votre type de TVA, vous \u00e9vitez ces soucis et vous assurez que tout est bien en ordre avec l\u2019administration.<\/p>\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #fed9db80;\">\n<p class=\"no-margin\">\u26a0\ufe0f  <b>Avant de faire quoi que ce soit, v\u00e9rifiez d\u2019abord votre type de TVA sur Intervat.<\/b><br \/>Suivez notre guide \u00e9tape par \u00e9tape ici :<br \/>\u200b<a href=\"https:\/\/help.accountable.eu\/fr\/articles\/11036503-comment-verifier-votre-type-de-tva-lors-de-la-creation-de-votre-compte-sur-accountable\" target=\"_blank\" class=\"intercom-content-link\">Comment v\u00e9rifier votre type de TVA lors de la cr\u00e9ation de votre compte sur Accountable<\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h1 id=\"h_ccb20f5063\">\u2728 Sc\u00e9nario 1 : Vous \u00eates d\u00e9j\u00e0 en retard pour la soumission des d\u00e9clarations des trimestres pr\u00e9c\u00e9dents<br \/><\/h1>\n<p class=\"no-margin\"><b>\u00c9tape 1 : \u00c9mettez des notes de cr\u00e9dit avant toute autre action<\/b><br \/>\u200b<br \/>Avant de faire quoi que ce soit, vous devez annuler toutes les factures cr\u00e9\u00e9es avec le mauvais type de TVA en \u00e9mettant des notes de cr\u00e9dit. Ces notes de cr\u00e9dit doivent \u00eatre rattach\u00e9es au trimestre en cours.<br \/>Cr\u00e9ez des notes de cr\u00e9dit \u00e0 la fois pour les factures de revenus et les factures de d\u00e9penses.<br \/>\u200b<\/p>\n<p class=\"no-margin\">Assurez-vous que les notes de cr\u00e9dit refl\u00e8tent exactement les factures d\u2019origine (sans TVA). <\/p>\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #fed9db80;\">\n<p class=\"no-margin\">\ud83e\uddfe <b>D\u00e9penses<\/b><\/p>\n<\/td>\n<td style=\"background-color: #d7efdc80;\">\n<p class=\"no-margin\">\ud83d\udcb0 <b>Revenus<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\">\u2705 Cr\u00e9ez des notes de cr\u00e9dit \u00e0 partir des m\u00eames factures d\u2019achat<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2705 Si la facture a \u00e9t\u00e9 cr\u00e9\u00e9e dans Accountable, g\u00e9n\u00e9rez une note de cr\u00e9dit \u00e0 partir de cette facture<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"no-margin\"><b>\u00c9tape 2 : Passez \u00e0 un abonnement sup\u00e9rieur pour pouvoir modifier votre type de TVA  : <\/b>Pour changer votre type de TVA, vous devez passer de l\u2019abonnement Comptabilit\u00e9 (GROW) \u00e0 Taxes ou MAX.<\/p>\n<p class=\"no-margin\">\n<p class=\"no-margin\"><b>\u00c9tape 3 : Modifiez votre type de TVA dans les param\u00e8tres<\/b><br \/>\u200b<br \/>Allez dans : <b>Compte &gt; Param\u00e8tres &gt; Taxes<\/b><br \/>\u200b<\/p>\n<p class=\"no-margin\">\u27a1\ufe0f Changez le type de TVA de <b>\u00ab\u00a0Franchise de TVA\u00a0\u00bb<\/b> \u00e0 <b>\u00ab\u00a0Assujetti \u00e0 la TVA\u00a0\u00bb<\/b><\/p>\n<p class=\"no-margin\">\u200b<\/p>\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A\" width=\"2884\" height=\"1560\" style=\"height: auto;\"><\/div>\n<ul>\n<li>\n<p class=\"no-margin\">N\u2019oubliez pas de cliquer sur <b>Sauvegarder<\/b>.<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479133604\/0ff14e435920d94eafbf09ed8954\/Screenshot+2025-04-16+at+14_27_06.png?expires=1778241600&amp;signature=8bab0bbc9984fbe532d82b788d1a0e7314267c83104250634da7d59abea2307d&amp;req=dSQgH8h9nodfXfMW3nq%2BgY%2BUVl%2FA%2B11ccvbnrDlJYYKhbRNWZ1kCY3u1dXOZ%0Aj0eltWJbEhZnTMShy4IYTlMhM7M%3D%0A\" width=\"2898\" height=\"1502\" style=\"height: auto;\"><\/div>\n<p class=\"no-margin\">\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\">\u26a0\ufe0f <b>Une fois la mise \u00e0 jour effectu\u00e9e, les nouvelles factures utiliseront automatiquement le bon type de TVA.<br \/>Cependant, toutes les factures cr\u00e9\u00e9es avec l\u2019ancien type de TVA devront \u00eatre corrig\u00e9es manuellement.<\/b><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"no-margin\">\n<p class=\"no-margin\"><b>\u00c9tape 4 : Contactez vos clients avant de cr\u00e9er de nouvelles factures<\/b><br \/>\u200b<br \/>Discutez des corrections \u00e0 apporter avec vos clients. Votre approche d\u00e9pendra de ce qu\u2019ils acceptent.<br \/>\u200b<br \/>Vous avez deux options :<\/p>\n<ul>\n<li>\n<p class=\"no-margin\"><b>Soit : Ajouter la TVA en plus du montant initial<\/b> :<br \/>\ud83d\udc49 Le client paie 21 % de TVA en suppl\u00e9ment.<\/p>\n<\/li>\n<\/ul>\n<ol>\n<li>\n<p class=\"no-margin\"><b>Ou: Inclure la TVA dans le montant initial<\/b> :<br \/>\ud83d\udc49 Vous prenez la TVA \u00e0 votre charge et l&rsquo;absorbez dans le prix total, ce qui r\u00e9duit votre revenu net.<\/p>\n<\/li>\n<\/ol>\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Type de vente<\/b><\/p>\n<\/td>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Action<\/b><\/p>\n<\/td>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Impact TVA<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Business (B2B) en Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Note de cr\u00e9dit + nouvelle facture + collecter la TVA (ou absorber la TVA)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb0 La TVA doit \u00eatre collect\u00e9e aupr\u00e8s du client ou absorb\u00e9e dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) en Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut TVA du \u00ab\u202fautre revenu\u202f\u00bb \u2192 (Param\u00e8tres avanc\u00e9s)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb8  Absorber la TVA dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Business (B2B) en dehors de la Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Note de cr\u00e9dit + nouvelle facture<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83c\udf0d Aucun impact TVA sur le montant collect\u00e9.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) dans l\u2019UE<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut TVA du \u00ab\u202fautre revenu\u202f\u00bb \u2192 (Param\u00e8tres avanc\u00e9s)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb8  Absorber la TVA   dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) hors de l\u2019UE<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut du \u00ab\u202fautre revenu\u202f\u00bb<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83c\udf0d Aucun impact TVA sur le montant collect\u00e9.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"no-margin\">\n<h4 id=\"h_9c47e251e6\">\u00c9tape 5 : Recr\u00e9er les factures<\/h4>\n<p class=\"no-margin\">Cr\u00e9ez de nouvelles factures de revenus et de d\u00e9penses avec le bon type de TVA.<\/p>\n<p class=\"no-margin\">Assurez-vous que ces factures sont bien li\u00e9es au trimestre en cours.<br \/>\u200b<\/p>\n<p class=\"no-margin\">\n<h1 id=\"h_a42478d529\">\u2728 R\u00e9capitulatif : Correction du type de TVA \u2013 <br \/>                                 Sc\u00e9nario 1 : (D\u00e9claration en retard)<\/h1>\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #e8e8e880;\">\n<p class=\"no-margin\"><b>\u00c9tape<\/b><\/p>\n<\/td>\n<td style=\"background-color: #fed9db80;\">\n<p class=\"no-margin\"><b>D\u00e9penses<\/b><\/p>\n<\/td>\n<td style=\"background-color: #d7efdc80;\">\n<p class=\"no-margin\"><b>Revenus<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>1. Note de cr\u00e9dit<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2705 Cr\u00e9er des notes de cr\u00e9dit en utilisant les m\u00eames factures d\u2019achat<br \/>\u200b<br \/>\u2705 Lier les notes de cr\u00e9dit au trimestre en cours \ud83d\udcce Ajouter le document original<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2705 Si cr\u00e9\u00e9 dans Accountable, g\u00e9n\u00e9rer une note de cr\u00e9dit \u00e0 partir de la facture<br \/>\u200b<br \/>\u2705 Lier les notes de cr\u00e9dit au trimestre en cours \ud83d\udcce Ajouter le document original<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>2. Mise \u00e0 niveau de l\u2019abonnement<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb3 Passer de Comptabilit\u00e9 (GROW) \u00e0 Taxes ou MAX.<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb3 M\u00eame chose que pour les d\u00e9penses<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>3. Modifier le type de TVA<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2699\ufe0f Aller dans <b>Compte &gt; Param\u00e8tres &gt; Taxes<\/b><br \/>Changer le type de TVA de <b>\u00ab Franchise \u00bb<\/b> \u00e0 <b>\u00ab Assujetti \u00e0 la TVA \u00bb<\/b><br \/>\u200b<br \/>\ud83d\udcbe Cliquer sur <b>Enregistrer<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2699\ufe0f M\u00eame chose que pour les d\u00e9penses<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>4. Contacter les clients<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">(non applicable)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcde Informer les clients de la correction <br \/>\u200b<\/p>\n<p class=\"no-margin\">\ud83d\udca1 Choisissez : ajouter la TVA <b>en plus<\/b> ou <b>l\u2019absorber<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>5. Recr\u00e9er les factures<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Cr\u00e9er de nouvelles factures de d\u00e9penses avec le bon type de TVA<br \/>\u200b<br \/>\ud83d\udccc Les lier au trimestre en cours<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Recr\u00e9er les factures de revenus avec le bon type de TVA<br \/>\u200b<br \/>\ud83d\udccc Liez-les au trimestre en cours<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>6. Envoyer les documents<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">(non applicable)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udce4 Envoyer la note de cr\u00e9dit et la nouvelle facture au client pour confirmation et paiement<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"no-margin\">\u26a0\ufe0f <b>Veuillez consulter le tableau de l\u2019\u00e9tape 4 pour les types de ventes et l\u2019impact TVA dans le cadre du Sc\u00e9nario 1.<\/b><\/p>\n<p class=\"no-margin\">\n<p class=\"no-margin\">\n<h1 id=\"h_e3f0cee20f\">\ud83d\udd52 Sc\u00e9nario 2 : Vous n\u2019\u00eates pas encore en retard pour la d\u00e9claration<\/h1>\n<h3 id=\"h_5f253e6d50\">\u00c9tape 1 : V\u00e9rifiez la fr\u00e9quence de d\u00e9claration TVA de votre client<\/h3>\n<ul>\n<li>\n<p class=\"no-margin\">Si votre client d\u00e9clare la TVA <b>trimestriellement<\/b> :<br \/>\u2003\ud83d\udc49 Vous pouvez modifier la facture directement (apr\u00e8s avoir effectu\u00e9 la mise \u00e0 niveau vers <b>Taxes ou MAX<\/b>).<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Si votre client d\u00e9clare la TVA <b>mensuellement<\/b> :<br \/>\u2003\ud83d\udc49 Vous devez d&rsquo;abord \u00e9mettre une <b>note de cr\u00e9dit<\/b> pour la facture d&rsquo;origine avant de proc\u00e9der \u00e0 la mise \u00e0 niveau de votre abonnement.<\/p>\n<\/li>\n<\/ul>\n<h4 id=\"h_01e57eb1c7\">Accordez-vous avec le client : <\/h4>\n<p class=\"no-margin\">Comme dans le sc\u00e9nario 1, mettez-vous d\u2019accord avec votre client sur l\u2019une des deux m\u00e9thodes de correction suivantes :<\/p>\n<ul>\n<li>\n<p class=\"no-margin\"><b>Ajouter la TVA<\/b> au montant initial (le client paie 21 % en plus).<br \/>\u200b<br \/>\u200b<b>Ou bien<\/b><br \/>\u200b<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\"><b>Inclure la TVA<\/b> dans le montant initial (vous absorbez la TVA).<\/p>\n<\/li>\n<\/ul>\n<hr>\n<h3 id=\"h_5df19a58cc\">\u00c9tape 2 : Mettez \u00e0 niveau votre abonnement<\/h3>\n<p class=\"no-margin\">\u27a1\ufe0f Passez de <b>Comptabilit\u00e9 (GROW)<\/b> \u00e0 <b>Taxes<\/b> ou <b>MAX<\/b>.<\/p>\n<hr>\n<h3 id=\"h_05383d2942\">\u00c9tape 3 : Modifiez votre type de TVA dans les param\u00e8tres<\/h3>\n<p class=\"no-margin\">\u27a1\ufe0f Allez dans <b>Compte &gt; Param\u00e8tres &gt; Taxes<\/b><br \/>\u27a1\ufe0f Changez le type de TVA de <b>\u00ab\u00a0Franchise\u00a0\u00bb<\/b> \u00e0 <b>\u00ab\u00a0Assujetti \u00e0 la TVA\u00a0\u00bb<\/b><br \/>\u200b<br \/>\u200b<\/p>\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479418766\/0736cbd7ab1be0bfbb24514c595c\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=d054988c51b6520c424aa147dbc2fd7d6d54e310ecf884991695069f2a40cbc3&amp;req=dSQgH81%2FlYZZX%2FMW3nq%2BgZlh00Om3jEM8vbPIoOfEP%2Bov7f2dtCzkNOhgWHw%0ANhXvuKWBpAhImh3plLlf7kHLyJk%3D%0A\" width=\"2884\" height=\"1560\" style=\"height: auto;\"><\/div>\n<ul>\n<li>\n<p class=\"no-margin\">N\u2019oubliez pas de cliquer sur <b>Sauvegarder<\/b>.<\/p>\n<p class=\"no-margin\">\n<\/li>\n<\/ul>\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479419245\/1e4e3060c06c5240ebb2c6ec4d18\/Screenshot+2025-04-16+at+14_27_06.png?expires=1778241600&amp;signature=dc7617a68bd44413a14edd2bf5e5ffbda06202ff0d54245ebd1d0c0c443555e9&amp;req=dSQgH81%2FlINbXPMW3nq%2BgR6YEa37i4nuD4hI7jh3cdMUN4znDQp5JOR1Hapt%0AfcW%2BW4WmFXVbPLUK1O7vBuKNzwQ%3D%0A\" width=\"2898\" height=\"1502\" style=\"height: auto;\"><\/div>\n<p class=\"no-margin\">\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\">\u26a0\ufe0f <b>Une fois la mise \u00e0 jour effectu\u00e9e, les nouvelles factures utiliseront automatiquement le bon type de TVA.<br \/>Cependant, toutes les factures cr\u00e9\u00e9es avec l\u2019ancien type de TVA devront \u00eatre corrig\u00e9es manuellement.<\/b><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3 id=\"h_6076d7a457\"><b>\u00c9tape 4 : Modifiez les anciennes factures<\/b><\/h3>\n<h3 id=\"h_5a6f774103\">Pour les <b>d\u00e9penses<\/b> :<\/h3>\n<ul>\n<li>\n<p class=\"no-margin\">Allez dans la section <b>D\u00e9penses<\/b> de l\u2019application.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">S\u00e9lectionnez chaque facture enregistr\u00e9e avec le mauvais type de TVA.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Ouvrez les <b>param\u00e8tres avanc\u00e9s<\/b>, modifiez le <b>type de TVA<\/b>, puis <b>sauvegardez<\/b>.<\/p>\n<p class=\"no-margin\">\n<\/li>\n<\/ul>\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1480998113\/3bc112a0db420c9197735f4634ad\/ScreenRecording2025-04-17at14_25_27-ezgif_com-speed.gif?expires=1778241600&amp;signature=03161a005eb32f6a7324df38a99bbc6b07edfe068816b2a83778363d6f6fcfdd&amp;req=dSQvFsB3lYBeWvMW3nq%2BgVsCoAZywwdIUcqDnL3RUMhoJN%2FmFmQiTb584zSA%0ADgJ1j6RbCpbHzQnFcVNx75Lr1Q4%3D%0A\" width=\"800\" height=\"415\" style=\"height: auto;\"><\/div>\n<p class=\"no-margin\">\n<h3 id=\"h_8aa62661c0\">Pour les <b>tickets de revenus<\/b> :<\/h3>\n<ul>\n<li>\n<p class=\"no-margin\">Allez dans <b>Revenus &gt; Tickets<\/b>.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">S\u00e9lectionnez l\u2019entr\u00e9e incorrecte.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Ouvrez les <b>param\u00e8tres avanc\u00e9s<\/b>, mettez \u00e0 jour le <b>type de TVA<\/b> et le <b>taux<\/b>, puis cliquez sur <b>Enregistrer<\/b>.<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1481021761\/0a8755bf3c061fefe19634864007\/ScreenRecording2025-04-17at14_42_41-ezgif_com-video-to-gif-converter.gif?expires=1778241600&amp;signature=85458a0bd5c59692bc00461eaa416ff164c6aba8393f10fdfcfade2f1514bc8a&amp;req=dSQvF8l8nIZZWPMW3nq%2Bgc%2FdTV0Ui3uKirCWbx2lrxgHzEuWppGYEFgCoRyd%0AgsINM8jVW83i91mqb0TIYuyt%2BUQ%3D%0A\" width=\"800\" height=\"415\" style=\"height: auto;\"><\/div>\n<p class=\"no-margin\">\n<h3 id=\"h_dac7fa4373\">Pour les <b>factures de revenus<\/b> :<\/h3>\n<ul>\n<li>\n<p class=\"no-margin\">Allez dans <b>Revenus<\/b> et s\u00e9lectionnez la facture incorrecte.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Cliquez sur <b>Modifier<\/b>.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Mettez \u00e0 jour les <b>informations de votre entreprise<\/b> ainsi que le <b>type de TVA<\/b>.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Supprimez puis recr\u00e9ez les articles avec le <b>bon type de TVA<\/b> et le <b>bon taux<\/b>.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Enregistrez la facture.<\/p>\n<\/li>\n<\/ul>\n<div class=\"intercom-container\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1481061265\/406f00fc155c232d049f568dd65c\/ScreenRecording2025-04-17at15_01_17-ezgif_com-speed.gif?expires=1778241600&amp;signature=a077a3ef0e610d695be28de094b6c40cb962876de1829011a277dedd25931eda&amp;req=dSQvF8l4nINZXPMW3nq%2BgXBlScw79QtB%2FSdlWRLY8guRksejDVhU93E1bwqr%0Af0u4RaT9RU%2FaA735QL4ClkS1CnI%3D%0A\" width=\"800\" height=\"415\" style=\"height: auto;\"><\/div>\n<p class=\"no-margin\">\n<p class=\"no-margin\">\n<p class=\"no-margin\">\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Type de vente<\/b><\/p>\n<\/td>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Action<\/b><\/p>\n<\/td>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\"><b>Impact TVA<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Business (B2B) en Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Note de cr\u00e9dit + nouvelle facture + collecter la TVA (ou absorber la TVA)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcb0 La TVA doit \u00eatre collect\u00e9e aupr\u00e8s du client ou absorb\u00e9e dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) en Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut TVA du \u00ab\u00a0revenu divers\u00a0\u00bb \u2192 (Param\u00e8tres avanc\u00e9s)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Absorbez la TVA dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Business (B2B) hors de Belgique<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Note de cr\u00e9dit + nouvelle facture<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83c\udf0d Aucun impact TVA sur le montant encaiss\u00e9.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) dans l\u2019UE<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut TVA du \u00ab\u00a0revenu divers\u00a0\u00bb \u2192 (Param\u00e8tres avanc\u00e9s)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe Absorbez la TVA dans le prix total.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #feedaf80;\">\n<p class=\"no-margin\"><b>Business to Consumer (B2C) hors UE<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u270f\ufe0f Modifier le statut du \u00ab\u00a0revenu divers\u00a0\u00bb<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83c\udf0d Aucun impact TVA sur le montant encaiss\u00e9.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"no-margin\">\n<p class=\"no-margin\">\n<h1 id=\"h_c09f90b3a5\">\ud83d\udd52 <b>R\u00e9capitulatif : Correction du type de TVA \u2013 <\/b><\/h1>\n<h1 id=\"h_c09f90b3a5\"><b>     Sc\u00e9nario 2 (d\u00e9claration de TVA pas encore due)<\/b><\/h1>\n<div class=\"intercom-interblocks-table-container\">\n<table role=\"presentation\">\n<tbody>\n<tr>\n<td style=\"background-color: #e3e7fa80;\">\n<p class=\"no-margin\">Etape<\/p>\n<\/td>\n<td style=\"background-color: #fed9db80;\">\n<p class=\"no-margin\">D\u00e9penses<\/p>\n<\/td>\n<td style=\"background-color: #d7efdc80;\">\n<p class=\"no-margin\">Revenus<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>1. V\u00e9rifiez la fr\u00e9quence de soumission de la TVA de votre client<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">(non applicable)<\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udd0d <b>V\u00e9rifiez la fr\u00e9quence de soumission de la TVA de votre client<\/b> :<br \/>\u200b<br \/>\u2022 <b>Trimestrielle<\/b> : Vous pouvez modifier la facture directement apr\u00e8s la mise \u00e0 niveau.<br \/>\u200b<br \/>\u2022 <b>Mensuelle<\/b> : Une note de cr\u00e9dit est requise avant la mise \u00e0 niveau.<br \/>\u200b<br \/>\ud83d\udcde Convenez avec le client de la m\u00e9thode de correction :<\/p>\n<p class=\"no-margin\">1. Ajouter la TVA en plus<br \/>2. Inclure la TVA dans le montant total<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>2. Mettez \u00e0 niveau votre abonnement<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2934\ufe0f Mettez \u00e0 niveau de <b>Comptabilit\u00e9 (GROW)<\/b> \u00e0 <b>Taxes<\/b> ou <b>MAX<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2934\ufe0f M\u00eame chose que pour les d\u00e9penses<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>3. Modifiez le type de TVA<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2699\ufe0f Allez dans <b>Compte &gt; Param\u00e8tres &gt; Taxes<\/b><br \/>\u200b<br \/>Changez le type de TVA de <b>Franchis\u00e9<\/b> \u00e0 <b>Assujetti \u00e0 la TVA<\/b><br \/>\u200b<br \/>\ud83d\udcbe Cliquez sur <b>Enregistrer<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\u2699\ufe0f M\u00eame chose que pour les d\u00e9penses<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p class=\"no-margin\"><b>4. Ajustez les anciennes factures<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83d\udcc1 Allez dans <b>D\u00e9penses<\/b><\/p>\n<p class=\"no-margin\">\u270f\ufe0f Ouvrez chaque facture concern\u00e9e<\/p>\n<p class=\"no-margin\">\u2699\ufe0f Utilisez les <b>Param\u00e8tres avanc\u00e9s<\/b> pour modifier le type de TVA<\/p>\n<p class=\"no-margin\">\ud83d\udcbe Cliquez sur <b>Enregistrer<\/b><\/p>\n<\/td>\n<td>\n<p class=\"no-margin\">\ud83e\uddfe <b>Tickets de revenus<\/b> :<\/p>\n<p class=\"no-margin\">1. Allez dans <b>Revenus &gt; Tickets<\/b><\/p>\n<p class=\"no-margin\">2. Modifiez via les <b>Param\u00e8tres avanc\u00e9s<\/b><\/p>\n<p class=\"no-margin\">3. Mettez \u00e0 jour le type et le taux de TVA<\/p>\n<p class=\"no-margin\">4. \ud83d\udcbe Cliquez sur <b>Enregistrer<\/b><br \/>\u200b<br \/>\ud83e\uddfe <b>Factures de revenus<\/b> :<\/p>\n<p class=\"no-margin\">1. Allez dans <b>Revenus &gt; Factures<\/b><\/p>\n<p class=\"no-margin\">2. Cliquez sur <b>Modifier<\/b><\/p>\n<p class=\"no-margin\">3. Mettez \u00e0 jour le <b>type de TVA<\/b><\/p>\n<p class=\"no-margin\">4. <b>Supprimez et r\u00e9encodez<\/b> les articles avec le bon type et taux de TVA<\/p>\n<p class=\"no-margin\">5. \ud83d\udcbe Cliquez sur <b>Enregistrer<\/b><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<hr>\n<p class=\"no-margin\">\n<p class=\"no-margin\">\u26a0\ufe0f <b>Veuillez consulter le tableau \u00e0 l&rsquo;\u00e9tape 4 pour conna\u00eetre le type de vente et l\u2019impact TVA dans le cadre du Sc\u00e9nario 2.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez s\u00e9lectionn\u00e9 le mauvais type de TVA ? Voici comment le corriger facilement dans Accountable pour rester en r\u00e8gle.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-20285","help_center","type-help_center","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable\" \/>\n<meta property=\"og:description\" content=\"Vous avez s\u00e9lectionn\u00e9 le mauvais type de TVA ? Voici comment le corriger facilement dans Accountable pour rester en r\u00e8gle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/\" \/>\n<meta property=\"og:site_name\" content=\"Accountable\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T08:19:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsMH7o7jcKr8eCxNiZqit2lhiCUYKM%3D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/\",\"name\":\"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/c9wnmh12\\\/1479129763\\\/bd5125a30d8e1a05cec166a105f5\\\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A\",\"datePublished\":\"2025-12-26T11:15:49+00:00\",\"dateModified\":\"2026-05-07T08:19:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/c9wnmh12\\\/1479129763\\\/bd5125a30d8e1a05cec166a105f5\\\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A\",\"contentUrl\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/c9wnmh12\\\/1479129763\\\/bd5125a30d8e1a05cec166a105f5\\\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"name\":\"Accountable\",\"description\":\"Your accountant and tax advisor on your smartphone\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\",\"name\":\"Accountable\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"Accountable\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/","og_locale":"fr_FR","og_type":"article","og_title":"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable","og_description":"Vous avez s\u00e9lectionn\u00e9 le mauvais type de TVA ? Voici comment le corriger facilement dans Accountable pour rester en r\u00e8gle.","og_url":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/","og_site_name":"Accountable","article_modified_time":"2026-05-07T08:19:20+00:00","og_image":[{"url":"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/","url":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/","name":"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ? - Accountable","isPartOf":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/#primaryimage"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/#primaryimage"},"thumbnailUrl":"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A","datePublished":"2025-12-26T11:15:49+00:00","dateModified":"2026-05-07T08:19:20+00:00","breadcrumb":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/#primaryimage","url":"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A","contentUrl":"https:\/\/downloads.intercomcdn.com\/i\/o\/c9wnmh12\/1479129763\/bd5125a30d8e1a05cec166a105f5\/Screenshot+2025-04-16+at+14_24_04.png?expires=1778241600&amp;signature=ed570b1734424b5e15297e322549a4464f44d433c0b4e5329dfcba10bc953c1a&amp;req=dSQgH8h8lIZZWvMW3nq%2BgfcK98WBV0x6re7bL7A%2BbTvZBgwm4QD%2F5VzsJQsM%0AH7o7jcKr8eCxNiZqit2lhiCUYKM%3D%0A"},{"@type":"BreadcrumbList","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/je-suis-assujetti-a-la-tva-mais-jai-selectionne-le-regime-de-la-franchise-dans-accountable-que-faire-maintenant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.accountable.eu\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/www.accountable.eu\/fr-be\/help-center\/"},{"@type":"ListItem","position":3,"name":"Je suis assujetti \u00e0 la TVA mais j\u2019ai s\u00e9lectionn\u00e9 le r\u00e9gime de la franchise dans Accountable \u2013 Que faire maintenant ?"}]},{"@type":"WebSite","@id":"https:\/\/www.accountable.eu\/fr-be\/#website","url":"https:\/\/www.accountable.eu\/fr-be\/","name":"Accountable","description":"Your accountant and tax advisor on your smartphone","publisher":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accountable.eu\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.accountable.eu\/fr-be\/#organization","name":"Accountable","url":"https:\/\/www.accountable.eu\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","contentUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","width":512,"height":512,"caption":"Accountable"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center"}],"about":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/types\/help_center"}],"version-history":[{"count":7,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20285\/revisions"}],"predecessor-version":[{"id":24686,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20285\/revisions\/24686"}],"wp:attachment":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=20285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}