{"id":20557,"date":"2025-12-26T12:16:01","date_gmt":"2025-12-26T11:16:01","guid":{"rendered":"https:\/\/www.accountable.eu\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/"},"modified":"2026-05-07T10:19:17","modified_gmt":"2026-05-07T08:19:17","slug":"est-ce-que-toutes-les-depenses-comptent-pour-la-tva","status":"publish","type":"help_center","link":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/","title":{"rendered":"Est-ce que toutes les d\u00e9penses comptent pour la TVA ?"},"content":{"rendered":"<p class=\"intercom-align-left\"><b>Non, vous ne pouvez pas d\u00e9duire la TVA sur toutes vos d\u00e9penses.<\/b><\/p>\n<p class=\"intercom-align-left\">Voici les 3 conditions n\u00e9cessaires pour pouvoir r\u00e9cup\u00e9rer une partie de la TVA sur vos d\u00e9penses professionnelles:<\/p>\n<p class=\"intercom-align-left\"><b>1. Seulement les d\u00e9penses avec une facture qui contient votre num\u00e9ro de TVA ont un impact sur votre TVA.<\/b><\/p>\n<p class=\"intercom-align-left\">Vous ne pouvez r\u00e9cup\u00e9rer de la TVA que si vous avez une facture d&rsquo;achat, non un simple re\u00e7u. Ces factures doivent contenir votre num\u00e9ro de TVA.<\/p>\n<p class=\"intercom-align-left\">Pour ces d\u00e9penses, faites attention de cocher la case \u00ab\u00a0Facture\u00a0\u00bb lorsque vous enregistrez votre d\u00e9pense.<\/p>\n<div class=\"intercom-container intercom-align-left\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A\" width=\"1495\" height=\"1090\" style=\"height: auto;\"><\/div>\n<p class=\"intercom-align-left\"><b>2. Seules les d\u00e9penses avec une preuve attach\u00e9e comptent.<\/b><\/p>\n<p class=\"intercom-align-left\">Nous ne prenons en compte que les d\u00e9penses avec leur preuve attach\u00e9e. C&rsquo;est utile en cas de contr\u00f4le fiscal.<\/p>\n<p class=\"intercom-align-left\"><b>3. Gardez \u00e0 l&rsquo;esprit que certaines cat\u00e9gories comptables ne permettent pas de r\u00e9cup\u00e9rer la TVA.<\/b><\/p>\n<p class=\"intercom-align-left\">Les restaurants ou encore les assurances ne sont typiquement pas d\u00e9ductibles pour la TVA. Mais pas de soucis, Accountable applique automatiquement ces r\u00e8gles.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pouvez-vous d\u00e9duire la TVA sur toutes vos d\u00e9penses ?<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-20557","help_center","type-help_center","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable\" \/>\n<meta property=\"og:description\" content=\"Pouvez-vous d\u00e9duire la TVA sur toutes vos d\u00e9penses ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/\" \/>\n<meta property=\"og:site_name\" content=\"Accountable\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T08:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/\",\"name\":\"Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/194726594\\\/5d8707f8bd7ad453146c8f70\\\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A\",\"datePublished\":\"2025-12-26T11:16:01+00:00\",\"dateModified\":\"2026-05-07T08:19:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/194726594\\\/5d8707f8bd7ad453146c8f70\\\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A\",\"contentUrl\":\"https:\\\/\\\/downloads.intercomcdn.com\\\/i\\\/o\\\/194726594\\\/5d8707f8bd7ad453146c8f70\\\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/help-center\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Est-ce que toutes les d\u00e9penses comptent pour la TVA ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"name\":\"Accountable\",\"description\":\"Your accountant and tax advisor on your smartphone\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\",\"name\":\"Accountable\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"Accountable\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/","og_locale":"fr_FR","og_type":"article","og_title":"Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable","og_description":"Pouvez-vous d\u00e9duire la TVA sur toutes vos d\u00e9penses ?","og_url":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/","og_site_name":"Accountable","article_modified_time":"2026-05-07T08:19:17+00:00","og_image":[{"url":"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/","url":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/","name":"Est-ce que toutes les d\u00e9penses comptent pour la TVA ? - Accountable","isPartOf":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/#primaryimage"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/#primaryimage"},"thumbnailUrl":"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A","datePublished":"2025-12-26T11:16:01+00:00","dateModified":"2026-05-07T08:19:17+00:00","breadcrumb":{"@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/#primaryimage","url":"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A","contentUrl":"https:\/\/downloads.intercomcdn.com\/i\/o\/194726594\/5d8707f8bd7ad453146c8f70\/Create+Expense+2+Update.png?expires=1778241600&amp;signature=4f2c57fc080a6bb930a742ae6caadaae2f121a89fa0eef9bbe7d247e6b7168e1&amp;req=dSkjEct4mIhbFb4V1XW4gfkKHTqpwzk0hLWgEDfoAVaQZuxBTsnDlhX%2BYBHZ%0AHixp5CwnGoB%2B0ptS1Cdckv8D%2Fw%3D%3D%0A"},{"@type":"BreadcrumbList","@id":"https:\/\/www.accountable.eu\/fr-be\/help-center\/est-ce-que-toutes-les-depenses-comptent-pour-la-tva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.accountable.eu\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/www.accountable.eu\/fr-be\/help-center\/"},{"@type":"ListItem","position":3,"name":"Est-ce que toutes les d\u00e9penses comptent pour la TVA ?"}]},{"@type":"WebSite","@id":"https:\/\/www.accountable.eu\/fr-be\/#website","url":"https:\/\/www.accountable.eu\/fr-be\/","name":"Accountable","description":"Your accountant and tax advisor on your smartphone","publisher":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accountable.eu\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.accountable.eu\/fr-be\/#organization","name":"Accountable","url":"https:\/\/www.accountable.eu\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","contentUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","width":512,"height":512,"caption":"Accountable"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center"}],"about":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/types\/help_center"}],"version-history":[{"count":7,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20557\/revisions"}],"predecessor-version":[{"id":24597,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/help_center\/20557\/revisions\/24597"}],"wp:attachment":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=20557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}