{"id":18176,"date":"2025-04-02T14:05:20","date_gmt":"2025-04-02T12:05:20","guid":{"rendered":"https:\/\/www.accountable.eu\/?p=18176"},"modified":"2025-04-02T14:05:21","modified_gmt":"2025-04-02T12:05:21","slug":"pension-pour-les-independants","status":"publish","type":"post","link":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/","title":{"rendered":"Quelle pension pour les ind\u00e9pendants\u2009?"},"content":{"rendered":"\n<p><strong>Les ind\u00e9pendants sont nombreux \u00e0 s\u2019inqui\u00e9ter \u00e0 propos de leur pension. D\u2019autres personnes la voient comme un frein \u00e0 se lancer dans l\u2019entrepreneuriat. En r\u00e9alit\u00e9, l\u2019id\u00e9e selon laquelle les ind\u00e9pendants toucheront toujours une petite pension n\u2019est pas tout \u00e0 fait correcte. Il est possible de l\u2019augmenter sensiblement en faisant des choix judicieux et en passant par l\u2019optimisation fiscale.<\/strong><\/p>\n\n\n\n<p><strong>Dans ce guide, nous r\u00e9pondons \u00e0 vos questions les plus br\u00fblantes&nbsp;: comment fonctionne la pension pour les ind\u00e9pendants en Belgique<\/strong><strong>\u2009<\/strong><strong>? Quel est le montant l\u00e9gal de la pension<\/strong><strong>\u2009<\/strong><strong>? Comment calculer ma pension en tant qu\u2019ind\u00e9pendant et comment puis-je la compl\u00e9ter<\/strong><strong>\u2009<\/strong><strong>?<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Votre pension l\u00e9gale en tant qu\u2019ind\u00e9pendant<\/strong><\/h2>\n\n\n\n<p>Tout comme les salari\u00e9s et les fonctionnaires, les ind\u00e9pendants ont droit \u00e0 une pension l\u00e9gale. Celle-ci est financ\u00e9e par les cotisations sociales que vous payez tout au long de votre carri\u00e8re.<\/p>\n\n\n\n<p><strong>Gr\u00e2ce aux r\u00e9formes et \u00e0 la mise en place de la PLCI et de l\u2019EIP (voir ci-apr\u00e8s), la pension des ind\u00e9pendants a augment\u00e9 ces derni\u00e8res ann\u00e9es.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Calcul de la pension l\u00e9gale<\/strong><\/h3>\n\n\n\n<p>Votre pension l\u00e9gale est calcul\u00e9e sur la base&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>de vos revenus professionnels sur lesquels vous avez vers\u00e9 des cotisations sociales<\/li>\n\n\n\n<li>le nombre d\u2019ann\u00e9es depuis lequel vous \u00eates ind\u00e9pendant(e)<\/li>\n\n\n\n<li>l\u2019\u00e2ge de la pension (actuellement 66 ans, mais 67 ans \u00e0 partir de 2030)<\/li>\n<\/ul>\n\n\n\n<p>Une carri\u00e8re compl\u00e8te est chiffr\u00e9e \u00e0 45 ans. Plus vous versez des cotisations sociales longtemps, plus votre pension sera \u00e9lev\u00e9e. Pour une carri\u00e8re compl\u00e8te de 45 ans, vous avez le droit \u00e0 une pension compl\u00e8te.<\/p>\n\n\n\n<p>Votre pension par trimestre est calcul\u00e9e comme suit&nbsp;: vos revenus imposables x 0,25 (trimestre) x le nombre de jours travaill\u00e9s. Ce montant est \u00e0 multiplier par 60&nbsp;% si vous \u00eates une personne isol\u00e9e ou par 75&nbsp;% si vous avez une pension de m\u00e9nage.&nbsp;<\/p>\n\n\n\n<p>\ud83d\udca1&nbsp;<a href=\"https:\/\/www.accountable.eu\/fr-be\/simulateur-de-pension\/\">Calculez votre pension mensuelle en quelques clics gr\u00e2ce \u00e0 notre simulateur de pension pratique.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La pension minimum pour ind\u00e9pendants<\/strong><\/h2>\n\n\n\n<p>Vos revenus ont baiss\u00e9 au cours de votre carri\u00e8re d\u2019ind\u00e9pendant\u2009? Vous aurez peut-\u00eatre droit \u00e0 la pension minimum.<\/p>\n\n\n\n<p>La pension minimum pour les ind\u00e9pendants pr\u00e9sentant <strong>une carri\u00e8re compl\u00e8te de 45 ans<\/strong> s\u2019\u00e9l\u00e8ve \u00e0&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>20\u00a0437,44\u00a0\u20ac par an pour les personnes isol\u00e9es<\/strong><\/li>\n\n\n\n<li><strong>25\u00a0538,78\u00a0\u20ac en cas de pension de m\u00e9nage<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Attention&nbsp;: vous devez au moins avoir une carri\u00e8re de 30 ans pour percevoir la pension minimum. Celle-ci est calcul\u00e9e au pro rata d\u2019une carri\u00e8re de 45 ans.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment compl\u00e9ter votre pension en tant qu\u2019ind\u00e9pendant\u2009?<\/strong><\/h2>\n\n\n\n<p>La pension l\u00e9gale pour ind\u00e9pendant est souvent insuffisante. Voil\u00e0 pourquoi il existe diff\u00e9rentes fa\u00e7ons de la compl\u00e9ter.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pension Libre Compl\u00e9mentaire pour Ind\u00e9pendants (PLCI)<\/strong><\/h3>\n\n\n\n<p>La PLCI est une mani\u00e8re fiscalement avantageuse de compl\u00e9ter la pension. Voici les avantages de la PLCI&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vous choisissez le montant que vous souhaitez investir, avec un maximum de 8,17\u00a0% de vos revenus imposables et maximum 4\u00a0000,44\u00a0\u20ac (en 2025).<\/li>\n\n\n\n<li>Les primes sont 100\u00a0% d\u00e9ductibles en frais professionnels, ce qui vous fait payer moins d\u2019imp\u00f4ts.<\/li>\n\n\n\n<li>Par cons\u00e9quent, vos cotisations sociales sont aussi r\u00e9duites.<\/li>\n\n\n\n<li>Vous profitez \u00e9galement d\u2019un avantage fiscal \u00e0 l\u2019\u00e2ge de la pension.<\/li>\n<\/ul>\n\n\n\n<p>Une situation gagnant-gagnant, donc, puisque vous \u00e9pargnez pour votre avenir tout en optimisant vos imp\u00f4ts et vos cotisations sociales.<\/p>\n\n\n\n<p>\ud83d\udca1&nbsp;<a href=\"https:\/\/www.accountable.eu\/fr-be\/blog\/plci-independants\/\">Plus d\u2019informations sur la PLCI\u2009? D\u00e9couvrez tout ce que vous devez savoir\u2009!<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Convention de Pension pour Travailleurs Ind\u00e9pendants (CPTI)<\/strong><\/h3>\n\n\n\n<p>Tout ind\u00e9pendant en personne physique peut souscrire une CPTI pour compl\u00e9ter sa pension. Voici les avantages de la CPTI&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il s\u2019agit d\u2019une option int\u00e9ressante pour \u00e9conomiser pour plus tard, \u00e9tant donn\u00e9 que la PLCI et l\u2019\u00e9pargne-pension individuelle sont plafonn\u00e9es.<\/li>\n\n\n\n<li>Vous avez droit \u00e0 une r\u00e9duction d\u2019imp\u00f4ts de 30\u00a0% sur les primes si votre pension totale n\u2019\u00e9quivaut pas \u00e0 plus de 80\u00a0% de vos revenus annuels bruts.<\/li>\n\n\n\n<li>C\u2019est vous qui d\u00e9cidez combien investir.<\/li>\n\n\n\n<li>Vous pouvez profiter d\u2019un rendement plus \u00e9lev\u00e9 qu\u2019avec la PLCI.<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udca1&nbsp;<a href=\"https:\/\/www.accountable.eu\/nl-be\/blog\/poz-pensioenovereenkomst-voor-zelfstandigen\/\">Int\u00e9ress\u00e9(e) par la CPTI\u2009? D\u00e9couvrez-en plus\u2009!<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Engagement Individuel de Pension (EIP)<\/strong><\/h3>\n\n\n\n<p>Les ind\u00e9pendants actifs en soci\u00e9t\u00e9 peuvent souscrire une EIP. Cette pension est financ\u00e9e par votre soci\u00e9t\u00e9 et est d\u00e9ductible en frais professionnels.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Autres fa\u00e7ons de compl\u00e9ter votre pension en tant qu\u2019ind\u00e9pendant<\/strong><\/h2>\n\n\n\n<p>En tant qu\u2019ind\u00e9pendant, vous pouvez choisir de compl\u00e9ter votre pension des mani\u00e8res suivantes&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019investissement dans l\u2019immobilier en achetant un bureau, un lieu de travail ou une habitation. Les int\u00e9r\u00eats sur l\u2019hypoth\u00e8que de la partie de votre habitation que vous utilisez pour votre activit\u00e9 d\u2019ind\u00e9pendant peuvent \u00eatre d\u00e9ductibles fiscalement.<\/li>\n\n\n\n<li>L\u2019investissement dans des actions, des EFT ou des cryptomonnaies pour obtenir un rendement potentiellement plus \u00e9lev\u00e9.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La pension pour ind\u00e9pendants \u00e0 titre principal ou \u00e0 titre compl\u00e9mentaire<\/strong><\/h2>\n\n\n\n<p>En tant qu\u2019ind\u00e9pendant \u00e0 titre principal, vous constituez votre pension comme d\u00e9crit ci-dessus. Vous \u00eates ind\u00e9pendant \u00e0 titre compl\u00e9mentaire\u2009? Votre pension d\u00e9pend alors de votre activit\u00e9 principale en tant que salari\u00e9 ou fonctionnaire.&nbsp;<\/p>\n\n\n\n<p>Attention&nbsp;: En tant qu\u2019ind\u00e9pendant compl\u00e9mentaire, vous pouvez constituer une pension \u00e0 partir du moment o\u00f9 vos cotisations sociales s\u2019\u00e9l\u00e8vent \u00e0 750&nbsp;\u20ac minimum. C\u2019est la condition pour ouvrir une PLCI ou une CPTI.<\/p>\n\n\n\n<p>\ud83d\udca1<a href=\"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-independant-complementaire\/\">D\u00e9couvrez tous les d\u00e9tails sur l\u2019\u00e9pargne-pension pour ind\u00e9pendants \u00e0 titre compl\u00e9mentaire.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Questions fr\u00e9quentes sur la pension d\u2019ind\u00e9pendant<\/strong><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1743595339421\"><strong class=\"schema-faq-question\"><strong>\u00c0 combien s\u2019\u00e9l\u00e8ve la pension d\u2019un ind\u00e9pendant en moyenne\u2009?<\/strong><\/strong> <p class=\"schema-faq-answer\">La pension pour ind\u00e9pendant d\u00e9pend de plusieurs facteurs. La pension moyenne varie entre 1\u00a0200 et 1\u00a0500\u00a0\u20ac. Elle peut \u00eatre plus haute si vous investissez dans des solutions comme la PLCI et la CPTI.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1743595347606\"><strong class=\"schema-faq-question\"><strong>Comment calculer ma future pension en tant qu\u2019ind\u00e9pendant\u2009?<\/strong><\/strong> <p class=\"schema-faq-answer\">Vous pouvez simuler votre pension en toute simplicit\u00e9 en vous connectant via Itsme sur <a href=\"http:\/\/mypension.be\/\">Mypension.be<\/a>. Vous obtiendrez une estimation de votre pension l\u00e9gale et compl\u00e9mentaire. Envie de la calculer encore plus rapidement\u2009? Utilisez <a href=\"https:\/\/www.accountable.eu\/fr-be\/simulateur-de-pension\/\">notre simulateur de pension<\/a>\u2009!<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1743595354476\"><strong class=\"schema-faq-question\"><strong>Comment puis-je augmenter ma pension en tant qu\u2019ind\u00e9pendant\u2009?<\/strong><\/strong> <p class=\"schema-faq-answer\">Vous pouvez compl\u00e9ter votre pension en souscrivant une PLCI ou une CPTI, en investissant dans l\u2019immobilier ou dans des actions, ou en ayant recours \u00e0 un EIP si vous avez une soci\u00e9t\u00e9.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1743595363873\"><strong class=\"schema-faq-question\"><strong>Quid de ma pension si mes revenus d\u2019ind\u00e9pendant sont faibles\u2009?<\/strong><\/strong> <p class=\"schema-faq-answer\">Si vous avez eu une carri\u00e8re compl\u00e8te de 45 ans, vous avez le droit \u00e0 une pension minimum. Si vous avez travaill\u00e9 moins de 45 ans, la pension minimum sera calcul\u00e9e au pro rata.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les ind\u00e9pendants sont nombreux \u00e0 s\u2019inqui\u00e9ter \u00e0 propos de leur pension. D\u2019autres personnes la voient comme un frein \u00e0 se lancer dans l\u2019entrepreneuriat. En r\u00e9alit\u00e9, l\u2019id\u00e9e selon laquelle les ind\u00e9pendants toucheront toujours une petite pension n\u2019est pas tout \u00e0 fait correcte. Il est possible de l\u2019augmenter sensiblement en faisant des choix judicieux et en passant [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":13193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[289,291],"tags":[307,312],"class_list":["post-18176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-independant-a-titre-principal","category-informations-pratiques","tag-frais-professionnels","tag-independant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combien de pension pour les ind\u00e9pendants ? - Accountable<\/title>\n<meta name=\"description\" content=\"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu&#039;ind\u00e9pendant ? Vous pouvez le lire ici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combien de pension pour les ind\u00e9pendants ? - Accountable\" \/>\n<meta property=\"og:description\" content=\"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu&#039;ind\u00e9pendant ? Vous pouvez le lire ici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/\" \/>\n<meta property=\"og:site_name\" content=\"Accountable\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T12:05:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T12:05:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"686\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Valesca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valesca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/\"},\"author\":{\"name\":\"Valesca\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/person\\\/e9b420257ec5e7ac236d337e8c3aa7ad\"},\"headline\":\"Quelle pension pour les ind\u00e9pendants\u2009?\",\"datePublished\":\"2025-04-02T12:05:20+00:00\",\"dateModified\":\"2025-04-02T12:05:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/\"},\"wordCount\":1122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AC_Blog_Illustration_Pension_14.png\",\"keywords\":[\"Frais pro\",\"Ind\u00e9pendant \u00e0 titre principal\"],\"articleSection\":[\"Ind\u00e9pendant \u00e0 titre principal\",\"Informations pratiques\"],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/\",\"name\":\"Combien de pension pour les ind\u00e9pendants ? - Accountable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AC_Blog_Illustration_Pension_14.png\",\"datePublished\":\"2025-04-02T12:05:20+00:00\",\"dateModified\":\"2025-04-02T12:05:21+00:00\",\"description\":\"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu'ind\u00e9pendant ? Vous pouvez le lire ici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595339421\"},{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595347606\"},{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595354476\"},{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595363873\"}],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AC_Blog_Illustration_Pension_14.png\",\"contentUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AC_Blog_Illustration_Pension_14.png\",\"width\":686,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle pension pour les ind\u00e9pendants\u2009?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"name\":\"Accountable\",\"description\":\"Your accountant and tax advisor on your smartphone\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#organization\",\"name\":\"Accountable\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"contentUrl\":\"https:\\\/\\\/www.accountable.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"Accountable\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/#\\\/schema\\\/person\\\/e9b420257ec5e7ac236d337e8c3aa7ad\",\"name\":\"Valesca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g\",\"caption\":\"Valesca\"}},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595339421\",\"position\":1,\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595339421\",\"name\":\"\u00c0 combien s\u2019\u00e9l\u00e8ve la pension d\u2019un ind\u00e9pendant en moyenne\u2009?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La pension pour ind\u00e9pendant d\u00e9pend de plusieurs facteurs. La pension moyenne varie entre 1\u00a0200 et 1\u00a0500\u00a0\u20ac. Elle peut \u00eatre plus haute si vous investissez dans des solutions comme la PLCI et la CPTI.\",\"inLanguage\":\"fr-BE\"},\"inLanguage\":\"fr-BE\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595347606\",\"position\":2,\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595347606\",\"name\":\"Comment calculer ma future pension en tant qu\u2019ind\u00e9pendant\u2009?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Vous pouvez simuler votre pension en toute simplicit\u00e9 en vous connectant via Itsme sur <a href=\\\"http:\\\/\\\/mypension.be\\\/\\\">Mypension.be<\\\/a>. Vous obtiendrez une estimation de votre pension l\u00e9gale et compl\u00e9mentaire. Envie de la calculer encore plus rapidement\u2009? Utilisez <a href=\\\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/simulateur-de-pension\\\/\\\">notre simulateur de pension<\\\/a>\u2009!\",\"inLanguage\":\"fr-BE\"},\"inLanguage\":\"fr-BE\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595354476\",\"position\":3,\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595354476\",\"name\":\"Comment puis-je augmenter ma pension en tant qu\u2019ind\u00e9pendant\u2009?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Vous pouvez compl\u00e9ter votre pension en souscrivant une PLCI ou une CPTI, en investissant dans l\u2019immobilier ou dans des actions, ou en ayant recours \u00e0 un EIP si vous avez une soci\u00e9t\u00e9.\",\"inLanguage\":\"fr-BE\"},\"inLanguage\":\"fr-BE\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595363873\",\"position\":4,\"url\":\"https:\\\/\\\/www.accountable.eu\\\/fr-be\\\/blog\\\/pension-pour-les-independants\\\/#faq-question-1743595363873\",\"name\":\"Quid de ma pension si mes revenus d\u2019ind\u00e9pendant sont faibles\u2009?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Si vous avez eu une carri\u00e8re compl\u00e8te de 45 ans, vous avez le droit \u00e0 une pension minimum. Si vous avez travaill\u00e9 moins de 45 ans, la pension minimum sera calcul\u00e9e au pro rata.\",\"inLanguage\":\"fr-BE\"},\"inLanguage\":\"fr-BE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combien de pension pour les ind\u00e9pendants ? - Accountable","description":"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu'ind\u00e9pendant ? Vous pouvez le lire ici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/","og_locale":"fr_FR","og_type":"article","og_title":"Combien de pension pour les ind\u00e9pendants ? - Accountable","og_description":"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu'ind\u00e9pendant ? Vous pouvez le lire ici.","og_url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/","og_site_name":"Accountable","article_published_time":"2025-04-02T12:05:20+00:00","article_modified_time":"2025-04-02T12:05:21+00:00","og_image":[{"width":686,"height":400,"url":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png","type":"image\/png"}],"author":"Valesca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Valesca","Dur\u00e9e de lecture est.":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#article","isPartOf":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/"},"author":{"name":"Valesca","@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/person\/e9b420257ec5e7ac236d337e8c3aa7ad"},"headline":"Quelle pension pour les ind\u00e9pendants\u2009?","datePublished":"2025-04-02T12:05:20+00:00","dateModified":"2025-04-02T12:05:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/"},"wordCount":1122,"commentCount":0,"publisher":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#organization"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png","keywords":["Frais pro","Ind\u00e9pendant \u00e0 titre principal"],"articleSection":["Ind\u00e9pendant \u00e0 titre principal","Informations pratiques"],"inLanguage":"fr-BE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/","url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/","name":"Combien de pension pour les ind\u00e9pendants ? - Accountable","isPartOf":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#primaryimage"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png","datePublished":"2025-04-02T12:05:20+00:00","dateModified":"2025-04-02T12:05:21+00:00","description":"Combien de pension touche un ind\u00e9pendant en Belgique ? Et comment augmenter sa pension en tant qu'ind\u00e9pendant ? Vous pouvez le lire ici.","breadcrumb":{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595339421"},{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595347606"},{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595354476"},{"@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595363873"}],"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#primaryimage","url":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png","contentUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2021\/10\/AC_Blog_Illustration_Pension_14.png","width":686,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.accountable.eu\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Quelle pension pour les ind\u00e9pendants\u2009?"}]},{"@type":"WebSite","@id":"https:\/\/www.accountable.eu\/fr-be\/#website","url":"https:\/\/www.accountable.eu\/fr-be\/","name":"Accountable","description":"Your accountant and tax advisor on your smartphone","publisher":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accountable.eu\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.accountable.eu\/fr-be\/#organization","name":"Accountable","url":"https:\/\/www.accountable.eu\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","contentUrl":"https:\/\/www.accountable.eu\/wp-content\/uploads\/2026\/04\/logo-512.png","width":512,"height":512,"caption":"Accountable"},"image":{"@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.accountable.eu\/fr-be\/#\/schema\/person\/e9b420257ec5e7ac236d337e8c3aa7ad","name":"Valesca","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/secure.gravatar.com\/avatar\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/842a00073a87c3c1af38f724115771bae6278a353edd8ee1e85161e791790047?s=96&d=mm&r=g","caption":"Valesca"}},{"@type":"Question","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595339421","position":1,"url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595339421","name":"\u00c0 combien s\u2019\u00e9l\u00e8ve la pension d\u2019un ind\u00e9pendant en moyenne\u2009?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La pension pour ind\u00e9pendant d\u00e9pend de plusieurs facteurs. La pension moyenne varie entre 1\u00a0200 et 1\u00a0500\u00a0\u20ac. Elle peut \u00eatre plus haute si vous investissez dans des solutions comme la PLCI et la CPTI.","inLanguage":"fr-BE"},"inLanguage":"fr-BE"},{"@type":"Question","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595347606","position":2,"url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595347606","name":"Comment calculer ma future pension en tant qu\u2019ind\u00e9pendant\u2009?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Vous pouvez simuler votre pension en toute simplicit\u00e9 en vous connectant via Itsme sur <a href=\"http:\/\/mypension.be\/\">Mypension.be<\/a>. Vous obtiendrez une estimation de votre pension l\u00e9gale et compl\u00e9mentaire. Envie de la calculer encore plus rapidement\u2009? Utilisez <a href=\"https:\/\/www.accountable.eu\/fr-be\/simulateur-de-pension\/\">notre simulateur de pension<\/a>\u2009!","inLanguage":"fr-BE"},"inLanguage":"fr-BE"},{"@type":"Question","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595354476","position":3,"url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595354476","name":"Comment puis-je augmenter ma pension en tant qu\u2019ind\u00e9pendant\u2009?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Vous pouvez compl\u00e9ter votre pension en souscrivant une PLCI ou une CPTI, en investissant dans l\u2019immobilier ou dans des actions, ou en ayant recours \u00e0 un EIP si vous avez une soci\u00e9t\u00e9.","inLanguage":"fr-BE"},"inLanguage":"fr-BE"},{"@type":"Question","@id":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595363873","position":4,"url":"https:\/\/www.accountable.eu\/fr-be\/blog\/pension-pour-les-independants\/#faq-question-1743595363873","name":"Quid de ma pension si mes revenus d\u2019ind\u00e9pendant sont faibles\u2009?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Si vous avez eu une carri\u00e8re compl\u00e8te de 45 ans, vous avez le droit \u00e0 une pension minimum. Si vous avez travaill\u00e9 moins de 45 ans, la pension minimum sera calcul\u00e9e au pro rata.","inLanguage":"fr-BE"},"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/posts\/18176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/comments?post=18176"}],"version-history":[{"count":0,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/posts\/18176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/media\/13193"}],"wp:attachment":[{"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/media?parent=18176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/categories?post=18176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.accountable.eu\/fr-be\/wp-json\/wp\/v2\/tags?post=18176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}